{"id":37978,"date":"2024-07-01T13:22:02","date_gmt":"2024-07-01T11:22:02","guid":{"rendered":"https:\/\/www.rewe-group.com\/de\/?post_type=press_release&#038;p=37978"},"modified":"2024-07-16T11:17:33","modified_gmt":"2024-07-16T09:17:33","slug":"lokale-produkte-mit-loql","status":"publish","type":"press_release","link":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/","title":{"rendered":"Lokale Produkte mit Loql\u00a0"},"content":{"rendered":"\n<div class=\"wp-block-myblocks-template-root template-root\">\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-margin-aside row-margin-aside my-row-block row-margin\">\n<div class=\"wp-block-myblocks-row-margin-aside-cell-aside row-cell row-margin-aside-cell-aside my-cell-block\"><div class=\"myblock-wrapper block-my-nl-icon-teaser\" data-module-name=\"Teaser Newsletter Icon\"><div class=\"myblock-wrapper\">\n    <a\n        class=\"twitter-icon-teaser nl-icon-teaser\"\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsletter\/\"\n        target=\"_blank\" rel=\"noopener noreferrer\"        data-module-name=\".teaser-nl-icon\"\n    >\n        <div class=\"contents\">\n            <h2>Unseren Newsletter abonnieren<\/h2>\n            <div class=\"entry-content\"><p>Melden Sie sich hier f\u00fcr den REWE Group Newsletter an und erhalten Sie aktuelle Informationen rund um die REWE Group.<\/p>\n<\/div>\n            <div class=\"link\">\n                <span class=\"arrow-link btn-white\">Zur Anmeldung<\/span>\n            <\/div>\n        <\/div>\n        <div class=\"icon\">\n            <div class=\"illustration\"><\/div>\n        <\/div>\n    <\/a>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-margin-aside-cell-main row-cell row-margin-aside-cell-main my-cell-block\"><div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            \n            <p><strong>Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt. Unter dem Leitbild \u201eLokale Lebensmittel auf jeden Teller\u201c f\u00f6rdert Loql die Zusammenarbeit von regionalen Anbieter:innen wie lokalen Manufakturen und Landwirt:innen mit B2B-Abnehmer:innen.<\/strong><\/p>\n<p>Die Evaluierung der ersten internen Pilotphase f\u00e4llt, sowohl bei den lokalen Produzent:innen als auch bei den Abnehmer:innen, sehr positiv aus. Thomas Vidic, Chief Technology Product Officer von Loql betont: \u201cDer Antrieb f\u00fcr uns ist, die Abl\u00e4ufe rund um Bestellung und Vermarktung digital so einfach wie m\u00f6glich zu machen. Dadurch haben unsere Nutzer:innen mehr Zeit f\u00fcr die wesentlichen T\u00e4tigkeiten, wie die leidenschaftliche Herstellung der Lebensmittel.\u201d Nun erfolgt schrittweise der Rollout in vielen weiteren Regionen. Interessierte Landwirt:innen und andere lokale Produzent:innen sowie Manufakturen k\u00f6nnen sich schon jetzt kostenlos auf der <a href=\"https:\/\/www.loql.com\/registrierung_produzentinnen\" target=\"_blank\" rel=\"noopener\">Registrierungsseite<\/a> von Loql anmelden.<\/p>\n        <\/div>\n\n            <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            <h2 class=\"smaller\">So einfach funktioniert\u00b4s <\/h2>\n            <p><span data-contrast=\"auto\">Die Plattform bietet eine unkomplizierte Bestellabwicklung, einfache Kommunikation und schnelle Vernetzungsm\u00f6glichkeiten per App und per Webportal. Viele verschiedene Nutzergruppen von Landwirt:innen \u00fcber Winzer:innen, B\u00e4cker:innen und Imker:innen bis hin zu Metzger:innen nutzen Loql bereits. Durch die App kommunizieren sie direkt mit REWE M\u00e4rkten, wickeln ihre Bestellungen effizient ab und k\u00f6nnen digitale Vermarktungsm\u00f6glichkeiten nutzen. Die Anbieter:innen haben die M\u00f6glichkeit, ihre lokalen Produkte \u00fcber Loql zu pr\u00e4sentieren und ihr Sortiment zu aktualisieren\u00a0<\/span> <span data-contrast=\"auto\">\u2013 und das ganz unkompliziert per App oder Web. Die integrierte Suchfunktion erm\u00f6glicht es dar\u00fcber hinaus, <\/span><span data-contrast=\"auto\">REWE M\u00e4rkte in der N\u00e4he zu finden und den Kontakt zu ihnen herzustellen. F\u00fcr die REWE Kaufleute wiederum dient Loql als Einkaufshelfer, indem sie die gew\u00fcnschten Produkte in ihren Warenkorb legen und unkompliziert bei den Produzent:innen bestellen, aber auch selber neue Produzent:innen finden k\u00f6nnen.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mit Loql ist nicht nur ein effizientes und unkompliziertes Instrument f\u00fcr das Sourcing lokaler Produkte entstanden. Das Startup schafft auch mehr Transparenz bei der Herkunft von Produkten &#8211; und untermauert die Regionalit\u00e4tsstrategie des Unternehmens.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n        <\/div>\n\n            <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            <h2 class=\"smaller\">Erfolgreicher Start zeigt: Lokalit\u00e4t im Fokus der Kund:innen <\/h2>\n            <p><span data-contrast=\"auto\">Der aktuelle &#8222;Shopping-Trend-Report 2024&#8220; von Bing! und Statista zeigt, dass die Themen Qualit\u00e4t, Regionalit\u00e4t und Saisonalit\u00e4t weiterhin die wichtigsten Kriterien f\u00fcr deutsche Verbraucher:innen beim Lebensmitteleinkauf sind. Hier setzt Loql an und zeigt erfolgreich, wie einfach Regionalit\u00e4t und damit auch der Schutz von Natur und Umwelt sein kann: <q>Der Ursprungsgedanke der St\u00e4rkung von regionalen Strukturen hat sich auch in der Praxis best\u00e4tigt. Die durchschnittliche Entfernung zwischen Produzent:innen und Abnehmer:innen betr\u00e4gt bei Bestellungen \u00fcber die Plattform 20,3 Kilometer,<\/q> erkl\u00e4rt Clemens Tsalikis, Chief Operating Officer von Loql. Rund zwei Drittel aller Bestellungen gingen dar\u00fcber hinaus direkt an Landwirt:innen. Das Start-up leistet damit einen wichtigen Beitrag zur Erweiterung der Netzwerke vieler Lebensmittelproduzent:innen und bereitet den Weg f\u00fcr mehr Regionalit\u00e4t auf unseren Tellern. Und das in besonders gro\u00dfer Vielfalt: Bei den landwirtschaftlichen Betrieben sind Obst und Gem\u00fcse sowie Eier besonders beliebt. Aber auch Weing\u00fcter, Metzgereien, Brennereien und Imkereien sind bei Loql vertreten und \u00fcberzeugen mit einem vielf\u00e4ltigen Angebot.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Lokal verwurzelt pflegen REWE Kaufleute in ganz Deutschland langj\u00e4hrige Partnerschaften zu lokalen Betrieben, zum Teil seit mehr als 20 Jahren. Loql bekr\u00e4ftigt diesen Ansatz und belegt, dass Erzeuger:innen REWE bereits ab einem Markt beliefern k\u00f6nnen. So st\u00e4rkt die REWE Group regionale Strukturen &#8211; als verl\u00e4sslicher Partner der deutschen Landwirt:innen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n        <\/div>\n\n            <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-article-explainer\" data-module-name=\"Explainer\"><div class=\"article-explainer\">\n            <div\n    class=\"explainer-slider type-text expanded\"\n    data-module-name=\".article-explainer\"\n>\n    <div class=\"explainer-slider__header\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\">\n        <h2 class=\"explainer-slider__title\">\u00dcber REWE<\/h2>    <\/div>\n    <div class=\"explainer-slider__main\">\n        <div class=\"explainer-slider__slider slider-len-1\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"explainer-slider__slide\">\n                                                                                <div class=\"explainer-slider__text-content entry-content\">\n                                <p>Mit einem Umsatz von 31,6 Mrd. Euro (2024), bundesweit mehr als 170.000 Mitarbeitenden und 3.800 M\u00e4rkten geh\u00f6rt die REWE Markt GmbH zu den f\u00fchrenden Unternehmen im deutschen Lebensmitteleinzelhandel. Die REWE- und nahkauf-M\u00e4rkte werden als Filialen oder durch selbstst\u00e4ndige Kaufleute betrieben. REWE geh\u00f6rt zur genossenschaftlichen REWE Group, die einer der f\u00fchrenden Handels- und Touristikkonzerne in Deutschland und Europa ist. Im Jahr 2024 erzielte das Unternehmen einen Gesamtau\u00dfenumsatz von \u00fcber 96,1 Milliarden Euro. Die 1927 gegr\u00fcndete REWE Group ist mit ihren rund 380.000 Besch\u00e4ftigten in 21 europ\u00e4ischen L\u00e4ndern pr\u00e4sent.<\/p>\n                            <\/div>\n                                            <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n    <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-article-explainer\" data-module-name=\"Explainer\"><div class=\"article-explainer\">\n            <div\n    class=\"explainer-slider type-text expanded\"\n    data-module-name=\".article-explainer\"\n>\n    <div class=\"explainer-slider__header\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\">\n        <h2 class=\"explainer-slider__title\">\u00dcber Loql<\/h2>    <\/div>\n    <div class=\"explainer-slider__main\">\n        <div class=\"explainer-slider__slider slider-len-1\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"explainer-slider__slide\">\n                                                                                <div class=\"explainer-slider__text-content entry-content\">\n                                <p><span class=\"TextRun SCXW146963951 BCX8\" lang=\"DE\" xml:lang=\"DE\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW146963951 BCX8\">Die Ende 2022 gegr\u00fcndete OC Food Solutions GmbH ist ein <\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">hun<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">d<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">ertprozent<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">iges Tochterunternehmen der REWE Group und bietet digitale L\u00f6sungen im Bereich des Lebensmittelhandels <\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">sowie <\/span><span class=\"NormalTextRun SCXW146963951 BCX8\">der Beschaffung von lokalen und handwerklich hergestellten Produkten. Mit der B2B-Plattform <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW146963951 BCX8\">Loql<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\"> werden regionale und lokale <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW146963951 BCX8\">Produzent:innen<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\"> und <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW146963951 BCX8\">Abnehmer:innen<\/span><span class=\"NormalTextRun SCXW146963951 BCX8\"> zusammengef\u00fchrt, Bestellprozesse digitalisiert und ein Ort f\u00fcr einfache und intuitive Order Abwicklung und Kommunikation geschaffen. Die Vision ist: Lokale Lebensmittel auf jeden Teller!<\/span><\/span><span class=\"EOP SCXW146963951 BCX8\" data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:0,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n                            <\/div>\n                                            <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n    <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-contact-person\" data-module-name=\"Kontaktperson\">        <div class=\"main-author__wrapper\">\n        <div class=\"main-author\">\n            <div class=\"main-author__image\">\n                <div class=\"person-avatar m\">\n                    <div class=\"focused-image-container\">\n    <img decoding=\"async\"\n        class=\"focused-image\"\n        data-focus-x=\"0.00\"\n        data-focus-y=\"0.00\"\n        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/12\/Andreas_Wegner-300x300.jpg\"\n        alt=\"Portr\u00e4t von Andreas Wegner\"\n                        loading=\"lazy\"\n         data-copyright=\"Portr\u00e4t von Andreas Wegner \u00a9 REWE Group \"    >\n<\/div>\n                <\/div>\n            <\/div>\n            <div class=\"main-author__text\">\n                <h2 class=\"main-author__author-gender\">Kontakt<\/h2>                <p class=\"main-author__name\">\n                    Andreas Wegner                <\/p>\n\n                                    <p class=\"main-author__title\">Head of Corporate Communications E-Commerce, Digital &amp; Technologie und Mediensprecher <\/p>\n                \n                                            <\/div>\n        <\/div>\n                    <div class=\"main-author__contact\">\n                                    <a href=\"tel:+49 221 149 1050\" class=\"main-author__contact-item phone\">+49 221 149 1050<\/a>\n                                                    <a href=\"mailto:presse@rewe-digital.com\" class=\"main-author__contact-item\" target=\"_blank\" rel=\"noopener noreferrer\">\n                        presse@rewe-digital.com                    <\/a>\n                            <\/div>\n            <\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-gray section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-post-slider\" data-module-name=\"Relevant Content Collection\">    <div class=\"posts-slider\">\n    <div class=\"posts-slider__inner row-margin-single\">\n        <div class=\"posts-slider__header\">\n            <h2 class=\"posts-slider__title\">Weiterlesen<\/h2>\n            \n                    <\/div>\n        <div class=\"posts-slider__slider\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/zwei-jahre-technologische-partnerschaft-so-meistert-blume2000-den-muttertags-peak-mit-fulfillmenttools\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/zwei-jahre-technologische-partnerschaft-so-meistert-blume2000-den-muttertags-peak-mit-fulfillmenttools\\\/&quot;,&quot;element_name&quot;:&quot;Zwei Jahre technologische Partnerschaft: So meistert BLUME2000 den Muttertags-Peak mit fulfillmenttools&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/05\/fulfillmenttools-und-blumen2000.jpg.png?t=2026071508\"\n                        alt=\"Aufgeklappter Laptop mit dem Blumen 2000 Shop.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Aufgeklappter Laptop mit dem Blumen 2000 Shop. \u00a9 Blumen2000\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">4. Mai 2026<\/p>\n                <h3 class=\"post-teaser__title\">Zwei Jahre technologische Partnerschaft: So meistert BLUME2000 den Muttertags-Peak mit fulfillmenttools<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"48065\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Zwei Jahre technologische Partnerschaft: So meistert BLUME2000 den Muttertags-Peak mit fulfillmenttools&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-taupe medium type-3questions\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/drei-fragen\/markus-bobenhausen-zum-ersten-drei-parteien-vertrag-im-gemueseanbau\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/drei-fragen\\\/markus-bobenhausen-zum-ersten-drei-parteien-vertrag-im-gemueseanbau\\\/&quot;,&quot;element_name&quot;:&quot;Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\\u00fcseanbau&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2021\/12\/markus-bodenhausen.jpg?t=2026071508\"\n                        alt=\"Portr\u00e4t von Markus Bobenhausen\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Markus Bobenhausen \u00a9 REWE Group\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <div><\/div>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">4. Februar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Drei Fragen an<span>Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\u00fcseanbau<\/span><\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47367\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\\u00fcseanbau&quot;,&quot;post_type&quot;:&quot;3questions&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/gruene-woche-2026-starke-signale-fuer-die-landwirtschaft-und-eine-besondere-auszeichnung-fuer-emilie-bourgoin\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/gruene-woche-2026-starke-signale-fuer-die-landwirtschaft-und-eine-besondere-auszeichnung-fuer-emilie-bourgoin\\\/&quot;,&quot;element_name&quot;:&quot;Gr\\u00fcne Woche 2026: Starke Signale f\\u00fcr die Landwirtschaft \\u2013 und eine besondere Auszeichnung f\\u00fcr Emilie Bourgoin\\u00a0\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/gruene-woche-2026-1.jpg?t=2026071508\"\n                        alt=\"Bild vom REWE Group Messestand auf der Gr\u00fcnen Woche 2026\"\n                        loading=\"lazy\"\n                         data-copyright=\"Bild vom REWE Group Messestand auf der Gr\u00fcnen Woche 2026 \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">29. Januar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Gr\u00fcne Woche 2026: Starke Signale f\u00fcr die Landwirtschaft \u2013 und eine besondere Auszeichnung f\u00fcr Emilie Bourgoin\u00a0\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47302\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Gr\\u00fcne Woche 2026: Starke Signale f\\u00fcr die Landwirtschaft \\u2013 und eine besondere Auszeichnung f\\u00fcr Emilie Bourgoin\\u00a0\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-taupe medium type-3questions\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/drei-fragen\/bernhard-pointner-zum-drei-parteien-vertrag-beim-zukunftsbauer\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/drei-fragen\\\/bernhard-pointner-zum-drei-parteien-vertrag-beim-zukunftsbauer\\\/&quot;,&quot;element_name&quot;:&quot;Bernhard Pointner zum Drei-Parteien-Vertrag beim \\u201eZukunftsbauer\\u201c&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/Portareat-von-Bernhard-Pointner.jpg?t=2026071508\"\n                        alt=\"Portr\u00e4t von Bernhard Pointner\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Bernhard Pointner \u00a9 Milchwerke Berchtesgadener Land Chiemgau eG\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <div><\/div>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">28. Januar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Drei Fragen an<span>Bernhard Pointner zum Drei-Parteien-Vertrag beim \u201eZukunftsbauer\u201c<\/span><\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47214\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Bernhard Pointner zum Drei-Parteien-Vertrag beim \\u201eZukunftsbauer\\u201c&quot;,&quot;post_type&quot;:&quot;3questions&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/vorreiter-im-deutschen-lebensmitteleinzelhandel-rewe-group-landfrisch-ag-und-erzeuger-starten-einzigartiges-partnerschaftsmodell-fuer-zukunftstraechtigen-gemueseanbau\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/vorreiter-im-deutschen-lebensmitteleinzelhandel-rewe-group-landfrisch-ag-und-erzeuger-starten-einzigartiges-partnerschaftsmodell-fuer-zukunftstraechtigen-gemueseanbau\\\/&quot;,&quot;element_name&quot;:&quot;Vorreiter im deutschen Lebensmitteleinzelhandel: REWE Group, Landfrisch AG und Erzeuger starten einzigartiges Partnerschaftsmodell f\\u00fcr zukunftstr\\u00e4chtigen Gem\\u00fcseanbau&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/gruene-woche-2026.jpg?t=2026071508\"\n                        alt=\"Von links nach rechts: Johannes von Eerde (Landfrisch AG), Labinot Elshani (Landfrisch AG), Markus von Bobenhausen (REWE Group), Dr. Carolin Weyers (REWE Group), Marc Rademacher (REWE Group), Heinz Stoffers (Stoffers Gem\u00fcsebau), Christian Berghs-Trienekens (BT Gem\u00fcse)\"\n                        loading=\"lazy\"\n                         data-copyright=\"Von links nach rechts: Johannes von Eerde (Landfrisch AG), Labinot Elshani (Landfrisch AG), Markus von Bobenhausen (REWE Group), Dr. Carolin Weyers (REWE Group), Marc Rademacher (REWE Group), Heinz Stoffers (Stoffers Gem\u00fcsebau), Christian Berghs-Trienekens (BT Gem\u00fcse) \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">19. Januar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Vorreiter im deutschen Lebensmitteleinzelhandel: REWE Group, Landfrisch AG und Erzeuger starten einzigartiges Partnerschaftsmodell f\u00fcr zukunftstr\u00e4chtigen Gem\u00fcseanbau<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47125\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Vorreiter im deutschen Lebensmitteleinzelhandel: REWE Group, Landfrisch AG und Erzeuger starten einzigartiges Partnerschaftsmodell f\\u00fcr zukunftstr\\u00e4chtigen Gem\\u00fcseanbau&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Nachhaltigkeit&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-taupe medium type-3questions\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/drei-fragen\/luca-burwitz-zur-gruenen-woche-2026\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/drei-fragen\\\/luca-burwitz-zur-gruenen-woche-2026\\\/&quot;,&quot;element_name&quot;:&quot;Luca Burwitz zur Gr\\u00fcnen Woche 2026&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"-0.02\"\n                        data-focus-y=\"0.61\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/Portrait_Luca-Burwitz-scaled.jpg?t=2026071508\"\n                        alt=\"Portr\u00e4t von Luca Burwitz\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Luca Burwitz \u00a9Jenni Prucha\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <div><\/div>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">13. Januar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Drei Fragen an<span>Luca Burwitz zur Gr\u00fcnen Woche 2026<\/span><\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47009\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Luca Burwitz zur Gr\\u00fcnen Woche 2026&quot;,&quot;post_type&quot;:&quot;3questions&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_plain medium\">\n    <a\n        class=\"post-teaser__inner\"\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/kurznotizen\/gemeinsame-verantwortung-rewe-group-kooperiert-mit-sifav\/\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/kurznotizen\\\/gemeinsame-verantwortung-rewe-group-kooperiert-mit-sifav\\\/&quot;,&quot;element_name&quot;:&quot;Gemeinsame Verantwortung: REWE Group kooperiert mit SIFAV&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div class=\"post-teaser__header\">\n            <h3 class=\"post-teaser__header-title\">Kurznotiz<\/h3>        <\/div>\n        <div class=\"post-teaser__body\">\n            <div class=\"post-teaser__timestamp\">\n                5. Januar 2026            <\/div>\n            <div class=\"plain-post-teaser__text\">\n                Gemeinsame\u00a0Verantwortung: REWE Group\u00a0kooperiert\u00a0mit\u00a0SIFAV\u00a0\u00a0\nDie REWE Group\u00a0schlie\u00dft\u00a0sich\u00a0der\u00a0internationalen\u00a0Nachhaltigkeitsinitiative\u00a0SIFAV (Sustainability Initiative Fruit and Vegetables) an.\u00a0Koordiniert\u00a0von der\u00a0globalen\u00a0Nachhaltigkeitsorganisation\u00a0IDH\u00a0bringt\u00a0die Initiative\u00a0Unternehmen\u00a0zusammen, um\u00a0weltweite\u00a0Lieferketten\u00a0f\u00fcr Obst und\u00a0Gem\u00fcse\u00a0konsequent\u00a0nachhaltiger\u00a0zu\u00a0gestalten und\u00a0\u00f6kologische\u00a0sowie\u00a0soziale\u00a0Verantwortung\u00a0in\u00a0allen\u00a0Prozessen\u00a0zu\u00a0verankern.\u00a0\nSIFAV\u00a0orientiert\u00a0sich\u00a0an\u00a0den UN-Nachhaltigkeitszielen\u00a0und der EU-Strategie\u00a0\u201eFarm to\u00a0Fork\u201c.\u00a0Im\u00a0Mittelpunkt\u00a0stehen\u00a0Klimaschutz,\u00a0verantwortungsvolle\u00a0Wasserbewirtschaftung, regenerative\u00a0Landwirtschaft,\u00a0existenzsichernde\u00a0L\u00f6hne\u00a0und\u00a0sichere\u00a0Arbeitsbedingungen\u00a0entlang\u00a0der\u00a0Lieferkette.\u00a0\u00a0\nMehr\u00a0\u00fcber\u00a0SIFAV:\u00a0SIFAV | Sustainability Initiative Fruit and Vegetables\u00a0\u00a0            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"46983\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Gemeinsame Verantwortung: REWE Group kooperiert mit SIFAV&quot;,&quot;post_type&quot;:&quot;sticky_note&quot;,&quot;post_category&quot;:&quot;Nachhaltigkeit&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-red medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/1-jahr-rewe-bonus-was-fuer-ein-erfolg\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/1-jahr-rewe-bonus-was-fuer-ein-erfolg\\\/&quot;,&quot;element_name&quot;:&quot;1 Jahr REWE Bonus \\u2013 Was f\\u00fcr ein Erfolg!\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/REWE-Bonus-Scanvorgang-an-der-Kasse.jpg?t=2026071508\"\n                        alt=\"\u00c4lterer Mann an REWE Kasse mit REWE Bonus auf dem Handy\"\n                        loading=\"lazy\"\n                         data-copyright=\"\u00c4lterer Mann an REWE Kasse mit REWE Bonus auf dem Handy \u00a9 REWE Markt\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <p class=\"new-post-teaser__type\">Story<\/p>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">5. Januar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">1 Jahr REWE Bonus \u2013 Was f\u00fcr ein Erfolg!\u00a0<\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"46966\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;1 Jahr REWE Bonus \\u2013 Was f\\u00fcr ein Erfolg!\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-white\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-twitter-icon-teaser\" data-module-name=\"Teaser LinkedIn Icon\"><div class=\"myblock-wrapper\">\n    <div class=\"linkedin-teaser\" data-module-name=\".linkedin-teaser\">\n        <div class=\"contents\">\n            <div class=\"contents-inner\">\n                <h2 class=\"typo-xl\">Die REWE Group auf  <\/h2>\n                <div class=\"entry-content\">\n                    <p data-pm-slice=\"1 1 []\">Auf unserem LinkedIn-Kanal informieren wir \u00fcber aktuelle Entwicklungen in der REWE Group sowie der Branche \u2013 von Digitalisierung bis Nachhaltigkeit.<\/p>\n                <\/div>\n                <p class=\"link\">\n                    <a\n                        href=\"https:\/\/www.linkedin.com\/company\/rewegroup\/posts\/\"\n                        class=\"arrow-link btn-white\"\n                        target=\"_blank\" rel=\"noopener noreferrer\"                    >\n                        Zum LinkedIn-Kanal                    <\/a>\n                <\/p>\n            <\/div>\n        <\/div>\n\n                    <div class=\"post-teaser post-teaser_default\">\n                <a\n                    href=\"https:\/\/www.linkedin.com\/posts\/rewegroup_csd-k%C3%B6ln-2026-activity-7480231155108249600-TLWf\/?utm_source=share&amp;utm_medium=member_desktop&amp;rcm=ACoAAEiSGI4BlYEA78AfIKxGpI88IWE7B9IF5KA\"\n                    target=\"_blank\" rel=\"noopener noreferrer\"                    class=\"post-teaser__inner\"\n                >\n                    <div class=\"post-teaser__background-wrapper\">\n                                                                                <img decoding=\"async\"\n                                class=\"cover-img\"\n                                src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/07\/CSD-Pride-Muenchen-1-768x1152.jpg\"\n                                alt=\"Teilnehmende eines Christopher Street Day mit zahlreichen Regenbogenflaggen in einer dicht gef\u00fcllten Menschenmenge.\"\n                                loading=\"lazy\"\n                                 data-copyright=\"Teilnehmende eines Christopher Street Day mit zahlreichen Regenbogenflaggen in einer dicht gef\u00fcllten Menschenmenge. \u00a9micha-fotografiert.de | Michael Zimmermann\" data-copyright-wrapper=\".post-teaser__inner\"                            >\n                                            <\/div>\n\n                    <div class=\"post-teaser__content-wrapper\">\n                        <div class=\"post-teaser__content\">\n                                                                                            <p class=\"post-teaser__note\">8. Juli 2026<\/p>\n                                                        <h2 class=\"post-teaser__title\">Sichtbarkeit z\u00e4hlt. Deshalb zeigen wir Jahr f\u00fcr Jahr Farbe. \ud83c\udf08 <\/h2>                        <\/div>\n                    <\/div>\n                <\/a>\n            <\/div>\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>REWE Startup l\u00e4dt nach erfolgreicher Testphase Landwirt:innen und Lebensmittelproduzent:innen zum Mitmachen ein<\/p>\n","protected":false},"featured_media":37985,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","nl_adhoc_sent":1,"footnotes":""},"categories":[8],"tags":[54,59],"sales_line":[],"focus_theme":[140],"class_list":["post-37978","press_release","type-press_release","status-publish","has-post-thumbnail","hentry","category-unternehmen","tag-digitalisierung","tag-landwirtschaft","focus_theme-starke-gemeinschaft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lokale Produkte mit Loql\u00a0 - REWE Group<\/title>\n<meta name=\"description\" content=\"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lokale Produkte mit Loql\u00a0\" \/>\n<meta property=\"og:description\" content=\"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/\" \/>\n<meta property=\"og:site_name\" content=\"REWE Group\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T09:17:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/partnerschaft-loql.jpg?t=2026070312\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/\",\"name\":\"Lokale Produkte mit Loql\u00a0 - REWE Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2024\\\/07\\\/partnerschaft-loql.jpg?t=2026071508\",\"datePublished\":\"2024-07-01T11:22:02+00:00\",\"dateModified\":\"2024-07-16T09:17:33+00:00\",\"description\":\"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2024\\\/07\\\/partnerschaft-loql.jpg?t=2026071508\",\"contentUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2024\\\/07\\\/partnerschaft-loql.jpg?t=2026071508\",\"width\":2560,\"height\":1707,\"caption\":\"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/lokale-produkte-mit-loql\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lokale Produkte mit Loql\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\",\"name\":\"REWE Group\",\"description\":\"Die Website der REWE Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lokale Produkte mit Loql\u00a0 - REWE Group","description":"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/","og_locale":"de_DE","og_type":"article","og_title":"Lokale Produkte mit Loql\u00a0","og_description":"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.","og_url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/","og_site_name":"REWE Group","article_modified_time":"2024-07-16T09:17:33+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/partnerschaft-loql.jpg?t=2026070312","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/","url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/","name":"Lokale Produkte mit Loql\u00a0 - REWE Group","isPartOf":{"@id":"https:\/\/www.rewe-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/#primaryimage"},"image":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/partnerschaft-loql.jpg?t=2026071508","datePublished":"2024-07-01T11:22:02+00:00","dateModified":"2024-07-16T09:17:33+00:00","description":"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt.","breadcrumb":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/#primaryimage","url":"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/partnerschaft-loql.jpg?t=2026071508","contentUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2024\/07\/partnerschaft-loql.jpg?t=2026071508","width":2560,"height":1707,"caption":"Mit dem Lebensmittel-Start-up \u201cLoql\u201d nutzt die REWE Group eine innovative Plattform, die regionale Produzent:innen und Lebensmittelh\u00e4ndler:innen miteinander vernetzt."},{"@type":"BreadcrumbList","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/lokale-produkte-mit-loql\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.rewe-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"Lokale Produkte mit Loql\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.rewe-group.com\/de\/#website","url":"https:\/\/www.rewe-group.com\/de\/","name":"REWE Group","description":"Die Website der REWE Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rewe-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/37978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/types\/press_release"}],"version-history":[{"count":21,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/37978\/revisions"}],"predecessor-version":[{"id":38705,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/37978\/revisions\/38705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media\/37985"}],"wp:attachment":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media?parent=37978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/categories?post=37978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/tags?post=37978"},{"taxonomy":"sales_line","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/sales_line?post=37978"},{"taxonomy":"focus_theme","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/focus_theme?post=37978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}