{"id":26909,"date":"2022-10-26T10:00:46","date_gmt":"2022-10-26T08:00:46","guid":{"rendered":"https:\/\/www.rewe-group.com\/de\/?post_type=press_release&#038;p=26909"},"modified":"2024-06-21T12:50:44","modified_gmt":"2024-06-21T10:50:44","slug":"rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro","status":"publish","type":"press_release","link":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/","title":{"rendered":"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro"},"content":{"rendered":"\n<div class=\"wp-block-myblocks-template-root template-root\">\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-margin-aside row-margin-aside my-row-block row-margin\">\n<div class=\"wp-block-myblocks-row-margin-aside-cell-aside row-cell row-margin-aside-cell-aside my-cell-block\"><div class=\"myblock-wrapper block-my-nl-icon-teaser\" data-module-name=\"Teaser Newsletter Icon\"><div class=\"myblock-wrapper\">\n    <a\n        class=\"twitter-icon-teaser nl-icon-teaser\"\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsletter\/\"\n        target=\"_blank\" rel=\"noopener noreferrer\"        data-module-name=\".teaser-nl-icon\"\n    >\n        <div class=\"contents\">\n            <h2>Unseren Newsletter abonnieren<\/h2>\n            <div class=\"entry-content\"><p>Melden Sie sich hier f\u00fcr den REWE Group Newsletter an und erhalten Sie aktuelle Informationen rund um die REWE Group.<\/p>\n<\/div>\n            <div class=\"link\">\n                <span class=\"arrow-link btn-white\">Zur Anmeldung<\/span>\n            <\/div>\n        <\/div>\n        <div class=\"icon\">\n            <div class=\"illustration\"><\/div>\n        <\/div>\n    <\/a>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-margin-aside-cell-main row-cell row-margin-aside-cell-main my-cell-block\"><div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            \n            <p>Hilfe, die dringend ben\u00f6tigt wird: Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland. So erhalten die Ausgabestellen in den n\u00e4chsten Tagen lang haltbare Lebensmittel im Wert von 2,64 Mio. Euro. Unterst\u00fctzt werden damit von Armut betroffene Menschen \u2013 vor allem Gefl\u00fcchtete, Erwerbslose, Senior:innen, Alleinerziehende und Jugendliche mit geringem Haushaltsbudget. Vom 10. bis 22.\u00a0 Oktober hatten bundesweit mehr als 3.700 REWE- und 450 nahkauf-M\u00e4rkte sowie der REWE Onlineshop Kund:innen dazu aufgerufen, eine Spendent\u00fcte f\u00fcr die Tafel vor Ort zu kaufen. Die Aktionswochen standen unter dem Motto <q>Gemeinsam Teller f\u00fcllen. Wir helfen vor Ort!<\/q><\/p>\n<p><q>Es ist bedr\u00fcckend, dass hierzulande immer mehr Menschen das Geld f\u00fcr eine gesunde und ausgewogene Ern\u00e4hrung fehlt. Die Tafeln \u00fcbernehmen hier eine besonders wichtige soziale und gesellschaftliche Verantwortung bei der Unterst\u00fctzung von armutsbetroffenen Menschen. Dabei d\u00fcrfen sie nicht allein gelassen werden. Das erneut hohe Niveau des Spendenergebnisses ist f\u00fcr mich der eindrucksvolle Beleg daf\u00fcr, dass der gesellschaftliche Zusammenhalt in Deutschland nach wie vor gelebt wird und die Solidarit\u00e4t unserer Kundinnen und Kunden mit den Tafel-G\u00e4sten ungebrochen ist<\/q>, sagt REWE Group-Bereichsvorstand Peter Maly.<\/p>\n<p><q>Immer mehr Menschen fragen aktuell die Unterst\u00fctzung der Tafeln an, weil sie sich Grundnahrungsmittel nicht mehr leisten k\u00f6nnen. Vielerorts gehen Lebensmittelspenden zur\u00fcck, die Ehrenamtlichen geraten an ihre Belastungsgrenzen. Die gespendeten Lebensmittel der REWE-T\u00fcten-Aktion helfen ganz direkt von Armut betroffenen Menschen. Wir bedanken uns ganz herzlich bei den Kundinnen und Kunden von REWE und nahkauf sowie beim Unternehmen selbst f\u00fcr die Solidarit\u00e4t in dieser schwierigen Zeit<\/q>, sagt Jochen Br\u00fchl, Vorsitzender Tafel Deutschland e. V.<\/p>\n<p>Die 2,35 Kilogramm schwere Spendent\u00fcte enthielt sechs mit der Tafel Deutschland vereinbarte Lebensmittel: Reis, Nudeln, Tomatencremesuppe, Salzstangen, M\u00fcsliriegel und Kekse. Diese konnten Kund:innen f\u00fcr 5 Euro kaufen und in einer Aktionsbox im Markt der lokal kooperierenden Tafel zur Verf\u00fcgung stellen. Nun holen ehrenamtliche Tafel-Mitarbeiter:innen die Lebensmittel ab und verteilen sie in den kommenden Wochen in den Ausgabestellen an die Tafel-G\u00e4ste. REWE selbst spendete den Tafeln noch ein weiteres Mal 200.000 Euro \u2013 nach 500.000 Euro als Soforthilfe zur Unterst\u00fctzung der Ukraine-Fl\u00fcchtlinge im April 2022.<\/p>\n<p>Seit 1996 kooperieren REWE und die Tafeln sehr eng miteinander. So geben die M\u00e4rkte und L\u00e4ger des Handelsunternehmens t\u00e4glich Lebensmittel an die lokalen Ausgabestellen ab. Dabei handelt es sich haupts\u00e4chlich um Frischeprodukte, die zwar nicht mehr verkauft, aber dennoch bedenkenlos verzehrt werden k\u00f6nnen. Hinzu kommen finanzielle Spenden sowie die Organisation und Durchf\u00fchrung von Aktionen unter Beteiligung der Kund:innen.<\/p>\n        <\/div>\n\n                    <div class=\"textblock__links\">\n                <a\n                    href=\"http:\/\/www.rewe.de\/tafel\"\n                    target=\"_blank\" rel=\"noopener noreferrer\"                    class=\"arrow-link\"\n                >\n                    Weitere Informationen zur Aktion                <\/a>\n            <\/div>\n            <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-article-explainer\" data-module-name=\"Explainer\"><div class=\"article-explainer\">\n            <div\n    class=\"explainer-slider type-text expanded\"\n    data-module-name=\".article-explainer\"\n>\n    <div class=\"explainer-slider__header\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\">\n        <h2 class=\"explainer-slider__title\">\u00dcber REWE<\/h2>    <\/div>\n    <div class=\"explainer-slider__main\">\n        <div class=\"explainer-slider__slider slider-len-1\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"explainer-slider__slide\">\n                                                                                <div class=\"explainer-slider__text-content entry-content\">\n                                <p>Mit einem Umsatz von 31,6 Mrd. Euro (2024), bundesweit mehr als 170.000 Mitarbeitenden und 3.800 M\u00e4rkten geh\u00f6rt die REWE Markt GmbH zu den f\u00fchrenden Unternehmen im deutschen Lebensmitteleinzelhandel. Die REWE- und nahkauf-M\u00e4rkte werden als Filialen oder durch selbstst\u00e4ndige Kaufleute betrieben. REWE geh\u00f6rt zur genossenschaftlichen REWE Group, die einer der f\u00fchrenden Handels- und Touristikkonzerne in Deutschland und Europa ist. Im Jahr 2024 erzielte das Unternehmen einen Gesamtau\u00dfenumsatz von \u00fcber 96,1 Milliarden Euro. Die 1927 gegr\u00fcndete REWE Group ist mit ihren rund 380.000 Besch\u00e4ftigten in 21 europ\u00e4ischen L\u00e4ndern pr\u00e4sent.<\/p>\n                            <\/div>\n                                            <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n    <\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-contact-person\" data-module-name=\"Kontaktperson\">        <div class=\"main-author__wrapper\">\n        <div class=\"main-author\">\n            <div class=\"main-author__image\">\n                <div class=\"person-avatar m\">\n                    <div class=\"focused-image-container\">\n    <img decoding=\"async\"\n        class=\"focused-image\"\n        data-focus-x=\"0.00\"\n        data-focus-y=\"0.00\"\n        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2020\/12\/Raimund_Esser-300x300.jpg\"\n        alt=\"Portr\u00e4t von Raimund Esser\"\n                        loading=\"lazy\"\n         data-copyright=\"Portr\u00e4t von Raimund Esser \u00a9 REWE Group\"    >\n<\/div>\n                <\/div>\n            <\/div>\n            <div class=\"main-author__text\">\n                <h2 class=\"main-author__author-gender\">Kontakt<\/h2>                <p class=\"main-author__name\">\n                    Raimund  Esser                <\/p>\n\n                                    <p class=\"main-author__title\">Head of Corporate Communications und Unternehmenssprecher REWE Markt<\/p>\n                \n                                            <\/div>\n        <\/div>\n                    <div class=\"main-author__contact\">\n                                    <a href=\"tel:+49 221 149 1050\" class=\"main-author__contact-item phone\">+49 221 149 1050<\/a>\n                                                    <a href=\"mailto:presse@rewe.de\" class=\"main-author__contact-item\" target=\"_blank\" rel=\"noopener noreferrer\">\n                        presse@rewe.de                    <\/a>\n                            <\/div>\n            <\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-gray section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-post-slider\" data-module-name=\"Relevant Content Collection\">    <div class=\"posts-slider\">\n    <div class=\"posts-slider__inner row-margin-single\">\n        <div class=\"posts-slider__header\">\n            <h2 class=\"posts-slider__title\">Weiterlesen<\/h2>\n            \n                    <\/div>\n        <div class=\"posts-slider__slider\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-kundinnen-zeigen-herz\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-kundinnen-zeigen-herz\\\/&quot;,&quot;element_name&quot;:&quot;REWE- und\\u00a0nahkauf-Kund:innen\\u00a0zeigen Herz&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/03\/tafeltueten-ergebnis-west-scaled.jpg?t=2026071508\"\n                        alt=\"Person mit Bo-Pl\u00fcschtier im Markt, dass eine Tafetl\u00fcte h\u00e4lt.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Person mit Bo-Pl\u00fcschtier im Markt, dass eine Tafetl\u00fcte h\u00e4lt. \u00a9REWE \" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">12. M\u00e4rz 2026<\/p>\n                <h3 class=\"post-teaser__title\">REWE- und\u00a0nahkauf-Kund:innen\u00a0zeigen Herz<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47711\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;REWE- und\\u00a0nahkauf-Kund:innen\\u00a0zeigen Herz&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/gemeinsam-teller-fuellen-bundesweite-rewe-und-nahkauf-spendenaktion-startet\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/gemeinsam-teller-fuellen-bundesweite-rewe-und-nahkauf-spendenaktion-startet\\\/&quot;,&quot;element_name&quot;:&quot;Gemeinsam Teller f\\u00fcllen: Bundesweite REWE- und nahkauf-Spendenaktion startet\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/02\/REWE-startet-wieder-die-Tafeltueten-Aktion.jpg?t=2026071508\"\n                        alt=\"Ein Einkaufswagen mit haltbaren Lebensmitteln wie Nudeln und Mehl steht im Vordergrund eines Supermarkts. Dahinter sind viele braune Papiert\u00fcten mit Recycling-Symbolen aufgestapelt. Auf dem Einkaufswagen befindet sich ein gr\u00fcnes Schild mit dem Hinweis auf eine Spendenaktion f\u00fcr die Tafel.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Ein Einkaufswagen mit haltbaren Lebensmitteln wie Nudeln und Mehl steht im Vordergrund eines Supermarkts. Dahinter sind viele braune Papiert\u00fcten mit Recycling-Symbolen aufgestapelt. Auf dem Einkaufswagen befindet sich ein gr\u00fcnes Schild mit dem Hinweis auf eine Spendenaktion f\u00fcr die Tafel. \u00a9REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">19. Februar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Gemeinsam Teller f\u00fcllen: Bundesweite REWE- und nahkauf-Spendenaktion startet\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47496\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Gemeinsam Teller f\\u00fcllen: Bundesweite REWE- und nahkauf-Spendenaktion startet\\u00a0&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-light medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/lionel-souque-mit-queermentor-role-model-award-2026-ausgezeichnet\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/lionel-souque-mit-queermentor-role-model-award-2026-ausgezeichnet\\\/&quot;,&quot;element_name&quot;:&quot;Lionel Souque mit Queermentor Role Model Award 2026 ausgezeichnet&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"-0.02\"\n                        data-focus-y=\"0.48\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/Lionel-Souque-Queer-Mentor-Award.jpg?t=2026071508\"\n                        alt=\"Portr\u00e4t von Lionel Souque in einem Rahmen in den Farben der LGBTQIA+ Bewegung\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Lionel Souque in einem Rahmen in den Farben der LGBTQIA+ Bewegung \u00a9 REWE Group\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <p class=\"new-post-teaser__type\">Story<\/p>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">28. Januar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Lionel Souque mit Queermentor Role Model Award 2026 ausgezeichnet<\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47256\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Lionel Souque mit Queermentor Role Model Award 2026 ausgezeichnet&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/veganuary-im-rewe-lieferservice-jeder-pflanzliche-einkauf-zaehlt\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/veganuary-im-rewe-lieferservice-jeder-pflanzliche-einkauf-zaehlt\\\/&quot;,&quot;element_name&quot;:&quot;Veganuary im REWE Lieferservice: Jeder pflanzliche Einkauf z\\u00e4hlt&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.16\"\n                        data-focus-y=\"0.20\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/Lieferservice-Veganuary.jpg?t=2026071508\"\n                        alt=\"Eine Person in roter Arbeitskleidung tr\u00e4gt eine rote Kiste voller frischer Lebensmittel wie Obst, Gem\u00fcse, Salat und Kr\u00e4uter in einem Treppenhaus.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Eine Person in roter Arbeitskleidung tr\u00e4gt eine rote Kiste voller frischer Lebensmittel wie Obst, Gem\u00fcse, Salat und Kr\u00e4uter in einem Treppenhaus. \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">19. Januar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Veganuary im REWE Lieferservice: Jeder pflanzliche Einkauf z\u00e4hlt<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47137\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Veganuary im REWE Lieferservice: Jeder pflanzliche Einkauf z\\u00e4hlt&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Nachhaltigkeit&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/27-generali-koeln-marathon-rewe-group-unterstuetzt-das-lauf-event-seit-24-jahren\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/27-generali-koeln-marathon-rewe-group-unterstuetzt-das-lauf-event-seit-24-jahren\\\/&quot;,&quot;element_name&quot;:&quot;27. Generali K\\u00f6ln Marathon: REWE Group unterst\\u00fctzt das Lauf-Event seit 24 Jahren\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2025\/09\/koeln-marathon.jpg?t=2026071508\"\n                        alt=\"Ein aufblasbares Tor mit dem Logo der REWE Group markiert das Ziel des K\u00f6ln Marathons. Zahlreiche Menschen sind um das Tor herum versammelt.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Ein aufblasbares Tor mit dem Logo der REWE Group markiert das Ziel des K\u00f6ln Marathons. Zahlreiche Menschen sind um das Tor herum versammelt.  \u00a9 Thomas F\u00e4hnrich\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">29. September 2025<\/p>\n                <h3 class=\"post-teaser__title\">27. Generali K\u00f6ln Marathon: REWE Group unterst\u00fctzt das Lauf-Event seit 24 Jahren\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"45736\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;27. Generali K\\u00f6ln Marathon: REWE Group unterst\\u00fctzt das Lauf-Event seit 24 Jahren\\u00a0&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-dark medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/solidaritaet-die-ankommt-330-000-spendentueten-fuer-die-tafeln\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/solidaritaet-die-ankommt-330-000-spendentueten-fuer-die-tafeln\\\/&quot;,&quot;element_name&quot;:&quot;Solidarit\\u00e4t, die ankommt: 330.000 Spendent\\u00fcten f\\u00fcr die Tafeln\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2025\/09\/tafeltueten-2025.jpg?t=2026071508\"\n                        alt=\"Stand mit Tafelt\u00fcten im Markt\"\n                        loading=\"lazy\"\n                         data-copyright=\"Stand mit Tafelt\u00fcten im Markt  \u00a9 REWE Group\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <p class=\"new-post-teaser__type\">Pressemitteilung<\/p>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">26. September 2025<\/p>\n                    <h3 class=\"post-teaser__title\">Solidarit\u00e4t, die ankommt: 330.000 Spendent\u00fcten f\u00fcr die Tafeln\u00a0<\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"45723\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Solidarit\\u00e4t, die ankommt: 330.000 Spendent\\u00fcten f\\u00fcr die Tafeln\\u00a0&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/tafeln-brauchen-dringend-haltbare-lebensmittel\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/tafeln-brauchen-dringend-haltbare-lebensmittel\\\/&quot;,&quot;element_name&quot;:&quot;Tafeln brauchen dringend haltbare Lebensmittel&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2025\/09\/rewe-tafeltueten-aktion-2025-1.jpg\"\n                        alt=\"Im Supermarkt an einer Kasse steht eine Papiert\u00fcte mit mehreren Lebensmitteln und dem sichtbaren Aufdruck \u201eGemeinsam Teller f\u00fcllen!\u201c auf dem Kassenband. Im Hintergrund sind Regale mit Konserven zu sehen, w\u00e4hrend eine Person dem Kassierenden gegen\u00fcbersteht.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Im Supermarkt an einer Kasse steht eine Papiert\u00fcte mit mehreren Lebensmitteln und dem sichtbaren Aufdruck \u201eGemeinsam Teller f\u00fcllen!\u201c auf dem Kassenband. Im Hintergrund sind Regale mit Konserven zu sehen, w\u00e4hrend eine Person dem Kassierenden gegen\u00fcbersteht. \u00a9REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">24. September 2025<\/p>\n                <h3 class=\"post-teaser__title\">Tafeln brauchen dringend haltbare Lebensmittel<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"45376\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Tafeln brauchen dringend haltbare Lebensmittel&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/pride-2025-rewe-group-setzt-ein-zeichen-fuer-vielfalt\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/pride-2025-rewe-group-setzt-ein-zeichen-fuer-vielfalt\\\/&quot;,&quot;element_name&quot;:&quot;Pride 2025: REWE Group setzt ein Zeichen f\\u00fcr Vielfalt&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2025\/08\/rewe-group-csd-2025.jpg?t=2026071508\"\n                        alt=\"Zwei Personen mit buntem Glitzer im Gesicht lachen in die Kamera und sind umgeben von bunten Luftballons.\"\n                        loading=\"lazy\"\n                         data-copyright=\" Zwei Personen mit buntem Glitzer im Gesicht lachen in die Kamera und sind umgeben von bunten Luftballons.  \u00a9 Michael Zimmermann\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">20. August 2025<\/p>\n                <h3 class=\"post-teaser__title\">Pride 2025: REWE Group setzt ein Zeichen f\u00fcr Vielfalt<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"45183\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Pride 2025: REWE Group setzt ein Zeichen f\\u00fcr Vielfalt&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-twitter-icon-teaser\" data-module-name=\"Teaser LinkedIn Icon\"><div class=\"myblock-wrapper\">\n    <div class=\"linkedin-teaser\" data-module-name=\".linkedin-teaser\">\n        <div class=\"contents\">\n            <div class=\"contents-inner\">\n                <h2 class=\"typo-xl\">Die REWE Group auf  <\/h2>\n                <div class=\"entry-content\">\n                    <p data-pm-slice=\"1 1 []\">Auf unserem LinkedIn-Kanal informieren wir \u00fcber aktuelle Entwicklungen in der REWE Group sowie der Branche \u2013 von Digitalisierung bis Nachhaltigkeit.<\/p>\n                <\/div>\n                <p class=\"link\">\n                    <a\n                        href=\"https:\/\/www.linkedin.com\/company\/rewegroup\/posts\/\"\n                        class=\"arrow-link btn-white\"\n                        target=\"_blank\" rel=\"noopener noreferrer\"                    >\n                        Zum LinkedIn-Kanal                    <\/a>\n                <\/p>\n            <\/div>\n        <\/div>\n\n                    <div class=\"post-teaser post-teaser_default\">\n                <a\n                    href=\"https:\/\/www.linkedin.com\/posts\/rewegroup_csd-k%C3%B6ln-2026-activity-7480231155108249600-TLWf\/?utm_source=share&amp;utm_medium=member_desktop&amp;rcm=ACoAAEiSGI4BlYEA78AfIKxGpI88IWE7B9IF5KA\"\n                    target=\"_blank\" rel=\"noopener noreferrer\"                    class=\"post-teaser__inner\"\n                >\n                    <div class=\"post-teaser__background-wrapper\">\n                                                                                <img decoding=\"async\"\n                                class=\"cover-img\"\n                                src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/07\/CSD-Pride-Muenchen-1-768x1152.jpg\"\n                                alt=\"Teilnehmende eines Christopher Street Day mit zahlreichen Regenbogenflaggen in einer dicht gef\u00fcllten Menschenmenge.\"\n                                loading=\"lazy\"\n                                 data-copyright=\"Teilnehmende eines Christopher Street Day mit zahlreichen Regenbogenflaggen in einer dicht gef\u00fcllten Menschenmenge. \u00a9micha-fotografiert.de | Michael Zimmermann\" data-copyright-wrapper=\".post-teaser__inner\"                            >\n                                            <\/div>\n\n                    <div class=\"post-teaser__content-wrapper\">\n                        <div class=\"post-teaser__content\">\n                                                                                            <p class=\"post-teaser__note\">8. Juli 2026<\/p>\n                                                        <h2 class=\"post-teaser__title\">Sichtbarkeit z\u00e4hlt. Deshalb zeigen wir Jahr f\u00fcr Jahr Farbe. \ud83c\udf08 <\/h2>                        <\/div>\n                    <\/div>\n                <\/a>\n            <\/div>\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kundenaktion ergibt 487.000 Spendent\u00fcten &#8211; Zeichen der Solidarit\u00e4t und Mitmenschlichkeit<\/p>\n","protected":false},"featured_media":26908,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","nl_adhoc_sent":1,"footnotes":""},"categories":[5],"tags":[57,31],"sales_line":[28,15],"focus_theme":[139],"class_list":["post-26909","press_release","type-press_release","status-publish","has-post-thumbnail","hentry","category-nachhaltigkeit","tag-foodwaste","tag-soziales-engagement","sales_line-nahkauf","sales_line-rewe","focus_theme-undefined"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro - REWE Group<\/title>\n<meta name=\"description\" content=\"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro\" \/>\n<meta property=\"og:description\" content=\"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"REWE Group\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T10:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/10\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026070309\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/\",\"name\":\"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro - REWE Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2022\\\/10\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508\",\"datePublished\":\"2022-10-26T08:00:46+00:00\",\"dateModified\":\"2024-06-21T10:50:44+00:00\",\"description\":\"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2022\\\/10\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508\",\"contentUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2022\\\/10\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508\",\"width\":2560,\"height\":1707,\"caption\":\"Kundenaktion ergibt 487.000 Spendent\u00fcten - Zeichen der Solidarit\u00e4t und Mitmenschlichkeit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\",\"name\":\"REWE Group\",\"description\":\"Die Website der REWE Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro - REWE Group","description":"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/","og_locale":"de_DE","og_type":"article","og_title":"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro","og_description":"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.","og_url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/","og_site_name":"REWE Group","article_modified_time":"2024-06-21T10:50:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/10\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026070309","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/","url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/","name":"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro - REWE Group","isPartOf":{"@id":"https:\/\/www.rewe-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/#primaryimage"},"image":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/10\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508","datePublished":"2022-10-26T08:00:46+00:00","dateModified":"2024-06-21T10:50:44+00:00","description":"Mit bundesweit rund 487.000 Spendent\u00fcten unterst\u00fctzen REWE, nahkauf und Kund:innen die Tafeln in Deutschland.","breadcrumb":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/#primaryimage","url":"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/10\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508","contentUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2022\/10\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmitteln.jpg?t=2026071508","width":2560,"height":1707,"caption":"Kundenaktion ergibt 487.000 Spendent\u00fcten - Zeichen der Solidarit\u00e4t und Mitmenschlichkeit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/rewe-und-nahkauf-helfen-tafeln-mit-lebensmittel-fuer-264-millionen-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.rewe-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"REWE und nahkauf helfen Tafeln mit Lebensmittel f\u00fcr 2,64 Millionen Euro"}]},{"@type":"WebSite","@id":"https:\/\/www.rewe-group.com\/de\/#website","url":"https:\/\/www.rewe-group.com\/de\/","name":"REWE Group","description":"Die Website der REWE Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rewe-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/26909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/types\/press_release"}],"version-history":[{"count":3,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/26909\/revisions"}],"predecessor-version":[{"id":26912,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/press_release\/26909\/revisions\/26912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media\/26908"}],"wp:attachment":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media?parent=26909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/categories?post=26909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/tags?post=26909"},{"taxonomy":"sales_line","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/sales_line?post=26909"},{"taxonomy":"focus_theme","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/focus_theme?post=26909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}