{"id":30144,"date":"2023-05-17T14:03:54","date_gmt":"2023-05-17T12:03:54","guid":{"rendered":"https:\/\/www.rewe-group.com\/de\/?post_type=opinion&#038;p=30144"},"modified":"2025-09-24T10:45:52","modified_gmt":"2025-09-24T08:45:52","slug":"wir-muessen-uns-gemeinsam-auf-den-weg-machen","status":"publish","type":"opinion","link":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/","title":{"rendered":"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c"},"content":{"rendered":"\n<div class=\"wp-block-myblocks-template-root template-root\">\n<div class=\"wp-block-myblocks-section block-section section-bg-white\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-opinion-title\" data-module-name=\"Meinung Headline\">    <div class=\"opinion-title margin-row-inner\">\n                    <h2 class=\"opinion-title__title\">Liebe Leser:innen,<\/h2>\n            <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            \n            <p>es ist beinahe 100 Jahre her, dass die genossenschaftliche REWE Group gegr\u00fcndet wurde. Wer jetzt aber glaubt, dass wir uns in Traditionen verlieren und Innovationen scheuen, der irrt: Zu den Werten, die uns pr\u00e4gen, z\u00e4hlt Innovationskraft ebenso wie Nachhaltigkeit oder der Sinn f\u00fcr die Gemeinschaft. Ein Beweis daf\u00fcr ist f\u00fcr mich das in diesem Jahr gegr\u00fcndete <a href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/kompetenzzentrum-landwirtschaft-miteinander-statt-uebereinander-reden\/\">Kompetenzzentrum Landwirtschaft<\/a> der REWE Group. Eine Neuheit im deutschen Lebensmittelhandel!<\/p>\n<p>Mit diesem Forum heben wir die Zusammenarbeit zwischen Handel und Landwirtschaft auf eine neue Ebene. Wir arbeiten gemeinsam aktiv an der Transformation der Agrarwirtschaft mit. Mit der Expertise aller Beteiligten diskutieren und entwickeln wir L\u00f6sungsans\u00e4tze, die zu konkreten Produkten in den Regalen von REWE oder PENNY f\u00fchren \u2013 und so auch die Verbraucherinnen und Verbraucher mitnehmen. Und diese Diskussionen werden wir auf Augenh\u00f6he f\u00fchren \u2013 das ist mir pers\u00f6nlich ein ganz besonderes Anliegen.<\/p>\n<p>Als selbstst\u00e4ndiger REWE-Kaufmann spielen lokale und regionale Produkte in meinen M\u00e4rkten eine gro\u00dfe Rolle. Meine Kundinnen und Kunden fragen nach Spargel, Eiern oder Erdbeeren vom Landwirt um die Ecke, den sie pers\u00f6nlich kennen. Sie wollen \u2013 so wie wir \u2013 diese regionalen Strukturen f\u00f6rdern und, wenn man so will, Heimat schmecken. Aus dieser engen Zusammenarbeit und diversen Gespr\u00e4chen mit Landwirt:innen sind mir aber auch die Herausforderungen der Branche bekannt. Ich verstehe beide Seiten. Auch weil ich selbst auf einem Bauernhof im Siebengebirge aufgewachsen bin. Ich habe selbst auf dem M\u00e4hdrescher gesessen, mich fr\u00fch morgens um K\u00fche, Bullen und H\u00fchner gek\u00fcmmert \u2013 kenne also die sch\u00f6nen, aber auch herausfordernden Momente der landwirtschaftlichen Arbeit.<\/p>\n        <\/div>\n\n            <\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-white\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-article-quote\" data-module-name=\"Zitat\"><div class=\"article-quote margin-row-inner\">\n    <div class=\"article-quote__inner border-content reweg-teaser-main\">\n        <div class=\"article-quote__main\">\n            <div class=\"article-quote__text\">\n                <blockquote class=\"entry-content article-quote-font-size-large\"><p>Ich bin stolz Aufsichtsratsvorsitzender eines Unternehmens zu sein, das neue Wege geht und das sich mit der praktischen Umsetzung von Agrarinnovationen befasst \u2013 und sich eben nicht in der Theorie verliert.<\/p>\n<\/blockquote>\n            <\/div>\n            <div class=\"article-quote__note\">\n                                <p class=\"article-quote__name\">Erich  Stockhausen, Selbstst\u00e4ndiger REWE-Kaufmann sowie ehemaliger Aufsichtsratsvorsitzender der REWE Group<\/p>\n            <\/div>\n        <\/div>\n        <div class=\"article-quote__person\">\n            <div class=\"person-avatar m\">\n                <div class=\"focused-image-container\">\n    <img decoding=\"async\"\n        class=\"focused-image\"\n        data-focus-x=\"0.00\"\n        data-focus-y=\"0.00\"\n        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen-768x549.jpg\"\n        alt=\"Portr\u00e4t von Erich Stockhausen\"\n                        loading=\"lazy\"\n         data-copyright=\"Portr\u00e4t von Erich Stockhausen \u00a9 REWE\"    >\n<\/div>\n            <\/div>\n            <p class=\"article-quote__name\">Erich  Stockhausen, Selbstst\u00e4ndiger REWE-Kaufmann sowie ehemaliger Aufsichtsratsvorsitzender der REWE Group<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            \n            <p>Regionale Lieferketten sind tief in unserer Kaufmannschaft verankert. Wir wollen und m\u00fcssen l\u00e4ndliche Strukturen erhalten. Das haben wir mit der <a href=\"https:\/\/regional.rewe.de\/lokal-partnerschaft\" target=\"_blank\" rel=\"noopener\">REWE-Lokalpartnerschaft<\/a> bewiesen und jetzt ist es Zeit f\u00fcr den n\u00e4chsten Schritt. Mir ist vollkommen klar, dass die notwendige Transformation ein langer und manchmal auch steiler Weg sein wird, aber: Wir m\u00fcssen uns gemeinsam auf den Weg machen. Wir m\u00fcssen den notwendigen Wandel gemeinsam gestalten, ohne Denkverbote, mit konkreten, regionalen Projekten, mit starken Partner:innen. Ich bin stolz Aufsichtsratsvorsitzender eines Unternehmens zu sein, das neue Wege geht und das sich mit der praktischen Umsetzung von Agrarinnovationen befasst \u2013 und sich eben nicht in der Theorie verliert. Auch weil wir die Landwirt:innen ernst nehmen. Ganz nach dem Credo: <q>Von den Menschen f\u00fcr die Menschen.<\/q><\/p>\n<p>Diesem Leitsatz folgen wir auch als selbstst\u00e4ndige REWE-Kaufleute. Wir m\u00f6chten unsere M\u00e4rkte f\u00fcr k\u00fcnftige Generationen erhalten. Auch unsere Kinder sollen noch Spa\u00df daran haben, die Nahversorgung der Bev\u00f6lkerung sicherzustellen, Treffpunkt f\u00fcr Dorf oder Veedel zu sein, und schlussendlich auch l\u00e4ndliche Strukturen zu f\u00f6rdern. Deshalb: Machen wir uns gemeinsam auf den Weg!<\/p>\n        <\/div>\n\n            <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-opinion-title\" data-module-name=\"Meinung Headline\">    <div class=\"opinion-title margin-row-inner\">\n                    <p class=\"opinion-title__sign\">Ihr<br \/>\r\nErich Stockhausen<\/p>\n            <\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-margin-aside row-margin-aside my-row-block row-margin\">\n<div class=\"wp-block-myblocks-row-margin-aside-cell-aside row-cell row-margin-aside-cell-aside my-cell-block\"><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-margin-aside-cell-main row-cell row-margin-aside-cell-main my-cell-block\"><div class=\"myblock-wrapper block-my-article-about-person\" data-module-name=\"\u00dcber Person\"><div class=\"article-about-person\">\n    <div class=\"article-about-person__inner\">\n        <div class=\"article-about-person__image\">\n            <div class=\"person-avatar m\">\n                <div class=\"focused-image-container\">\n    <img decoding=\"async\"\n        class=\"focused-image\"\n        data-focus-x=\"0.00\"\n        data-focus-y=\"0.00\"\n        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen-300x214.jpg\"\n        alt=\"Portr\u00e4t von Erich Stockhausen\"\n                        loading=\"lazy\"\n         data-copyright=\"Portr\u00e4t von Erich Stockhausen \u00a9 REWE\"    >\n<\/div>\n            <\/div>\n        <\/div>\n        <div class=\"article-about-person__text\">\n            <h2 class=\"article-about-person__about\">\u00dcber:<\/h2>            <p class=\"article-about-person__name\">\n                Erich  Stockhausen            <\/p>\n\n                            <p class=\"article-about-person__title\">Selbstst\u00e4ndiger REWE-Kaufmann sowie ehemaliger Aufsichtsratsvorsitzender der REWE Group<\/p>\n            \n                    <\/div>\n    <\/div>\n<\/div>\n<\/div>\n\n<div class=\"myblock-wrapper block-my-article-explainer\" data-module-name=\"Explainer\"><div class=\"article-explainer\">\n            <div\n    class=\"explainer-slider type-text expanded\"\n    data-module-name=\".article-explainer\"\n>\n    <div class=\"explainer-slider__header\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\">\n        <h2 class=\"explainer-slider__title\">\u00dcber die REWE Group<\/h2>    <\/div>\n    <div class=\"explainer-slider__main\">\n        <div class=\"explainer-slider__slider slider-len-1\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"explainer-slider__slide\">\n                                                                                <div class=\"explainer-slider__text-content entry-content\">\n                                <p>Die genossenschaftliche REWE Group ist einer der f\u00fchrenden Handels- und Touristikkonzerne in Deutschland und Europa. Im Jahr 2025 erzielte das Unternehmen einen Gesamtau\u00dfenumsatz von \u00fcber 100 Milliarden Euro. Die 1927 gegr\u00fcndete REWE Group ist mit ihren rund 380.000 Besch\u00e4ftigten in 21 europ\u00e4ischen L\u00e4ndern pr\u00e4sent.<\/p>\n<p>Zu den Vertriebslinien z\u00e4hlen Super- und Verbraucherm\u00e4rkte der Marken REWE, nahkauf sowie BILLA und ADEG, der Discounter PENNY, IKI, die Drogeriem\u00e4rkte BIPA sowie die Baum\u00e4rkte von toom. Hinzu kommen die Convenience-M\u00e4rkte REWE To Go, REWE express und die E-Commerce-Aktivit\u00e4ten REWE Liefer- und Abholservice sowie Zooroyal und Weinfreunde. Die Lekkerland Gruppe umfasst die Gro\u00dfhandels-Aktivit\u00e4ten der Unternehmensgruppe im Bereich der Unterwegsversorgung. Zur Touristik geh\u00f6ren unter dem Dach der DERTOUR Group \u00fcber 2.000 Reiseb\u00fcros, Veranstalter sowie Hotelmarken und Online-Reiseportale.<\/p>\n                            <\/div>\n                                            <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n    <\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-gray section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-post-slider\" data-module-name=\"Relevant Content Collection\">    <div class=\"posts-slider\">\n    <div class=\"posts-slider__inner row-margin-single\">\n        <div class=\"posts-slider__header\">\n            <h2 class=\"posts-slider__title\">Weiterlesen<\/h2>\n            \n                    <\/div>\n        <div class=\"posts-slider__slider\">\n            <ul class=\"rwgs__inner\">\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/von-null-auf-wau-rewe-kaufmann-simon-bacher-auf-seinem-weg-zum-ersten-zooroyal-fachmarkt-in-nrw\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/von-null-auf-wau-rewe-kaufmann-simon-bacher-auf-seinem-weg-zum-ersten-zooroyal-fachmarkt-in-nrw\\\/&quot;,&quot;element_name&quot;:&quot;Von Null auf Wau: REWE-Kaufmann Simon Bacher auf seinem Weg zum ersten\\u00a0ZooRoyal-Fachmarkt in NRW\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/06\/Simon-Bacher-REWE-Kaufmann-scaled.jpg?t=2026071510\"\n                        alt=\"REWE-Kaufmann, Simon Bacher f\u00fcttert zwei geh\u00f6rnte Ziegen auf einer gr\u00fcnen Wiese mit Karotten aus einer Futterschale.\"\n                        loading=\"lazy\"\n                         data-copyright=\"REWE-Kaufmann, Simon Bacher f\u00fcttert zwei geh\u00f6rnte Ziegen auf einer gr\u00fcnen Wiese mit Karotten aus einer Futterschale. \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">1. Juli 2026<\/p>\n                <h3 class=\"post-teaser__title\">Von Null auf Wau: REWE-Kaufmann Simon Bacher auf seinem Weg zum ersten\u00a0ZooRoyal-Fachmarkt in NRW\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"48819\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Von Null auf Wau: REWE-Kaufmann Simon Bacher auf seinem Weg zum ersten\\u00a0ZooRoyal-Fachmarkt in NRW\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/frauen-in-der-genossenschaft-mit-einem-eigenen-markt-belohnt-man-sich-selbst\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/frauen-in-der-genossenschaft-mit-einem-eigenen-markt-belohnt-man-sich-selbst\\\/&quot;,&quot;element_name&quot;:&quot;Frauen in der Genossenschaft: \\u201eMit einem eigenen Markt belohnt man sich selbst\\u201c&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/05\/Kristin-Naumann.jpg?t=2026071510\"\n                        alt=\"Portr\u00e4t von Kristin Naumann\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Kristin Naumann \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">11. Mai 2026<\/p>\n                <h3 class=\"post-teaser__title\">Frauen in der Genossenschaft: \u201eMit einem eigenen Markt belohnt man sich selbst\u201c<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"48156\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Frauen in der Genossenschaft: \\u201eMit einem eigenen Markt belohnt man sich selbst\\u201c&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-press_release\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/pressemitteilungen\/nachhaltig-innovativ-und-laenger-haltbar-rewe-group-setzt-mit-pfluecksalaten-neuen-standard-im-hydroponik-anbau\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/pressemitteilungen\\\/nachhaltig-innovativ-und-laenger-haltbar-rewe-group-setzt-mit-pfluecksalaten-neuen-standard-im-hydroponik-anbau\\\/&quot;,&quot;element_name&quot;:&quot;Nachhaltig, innovativ\\u00a0und l\\u00e4nger haltbar:\\u00a0REWE Group\\u00a0setzt\\u00a0mit\\u00a0Pfl\\u00fccksalaten\\u00a0neuen Standard im\\u00a0Hydroponik-Anbau\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/03\/Hydroponik-Anbau.png?t=2026071510\"\n                        alt=\"Ein gro\u00dfes Gew\u00e4chshaus zeigt dicht bepflanzte Reihen von gr\u00fcnem Salat in einer hydroponischen Anlage. Die Pflanzen wachsen in langen Beeten.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Ein gro\u00dfes Gew\u00e4chshaus zeigt dicht bepflanzte Reihen von gr\u00fcnem Salat in einer hydroponischen Anlage. Die Pflanzen wachsen in langen Beeten. \u00a9 Endless Summer\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Pressemitteilung<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">9. M\u00e4rz 2026<\/p>\n                <h3 class=\"post-teaser__title\">Nachhaltig, innovativ\u00a0und l\u00e4nger haltbar:\u00a0REWE Group\u00a0setzt\u00a0mit\u00a0Pfl\u00fccksalaten\u00a0neuen Standard im\u00a0Hydroponik-Anbau\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47575\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Nachhaltig, innovativ\\u00a0und l\\u00e4nger haltbar:\\u00a0REWE Group\\u00a0setzt\\u00a0mit\\u00a0Pfl\\u00fccksalaten\\u00a0neuen Standard im\\u00a0Hydroponik-Anbau\\u00a0&quot;,&quot;post_type&quot;:&quot;press_release&quot;,&quot;post_category&quot;:&quot;Sortiment&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/sebastian-stein-vom-nahkauf-vertriebschef-zum-rewe-kaufmann\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/sebastian-stein-vom-nahkauf-vertriebschef-zum-rewe-kaufmann\\\/&quot;,&quot;element_name&quot;:&quot;Sebastian Stein: Vom nahkauf-Vertriebschef zum REWE-Kaufmann\\u00a0\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.15\"\n                        data-focus-y=\"0.47\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/02\/Sebastian-Stein.jpg?t=2026071510\"\n                        alt=\"Portr\u00e4t von Sebastian Stein vor dem Hintergrund der REWE Supermarkt.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Sebastian Stein vor dem Hintergrund der REWE Supermarkt. \u00a9REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">24. Februar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Sebastian Stein: Vom nahkauf-Vertriebschef zum REWE-Kaufmann\u00a0\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47473\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Sebastian Stein: Vom nahkauf-Vertriebschef zum REWE-Kaufmann\\u00a0\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-red medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/vom-marktmanager-zum-kaufmann-in-kiel\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/vom-marktmanager-zum-kaufmann-in-kiel\\\/&quot;,&quot;element_name&quot;:&quot;Vom Marktmanager zum Kaufmann in Kiel\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.06\"\n                        data-focus-y=\"0.70\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/Moritz-Breske.jpg?t=2026071510\"\n                        alt=\"Portaet von REWE-Kaufmann Moritz Breske.\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Moritz Breske.\u00a0\u00a9REWE Group\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <p class=\"new-post-teaser__type\">Story<\/p>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">9. Februar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Vom Marktmanager zum Kaufmann in Kiel\u00a0<\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47184\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Vom Marktmanager zum Kaufmann in Kiel\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Unternehmen&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-taupe medium type-3questions\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/drei-fragen\/markus-bobenhausen-zum-ersten-drei-parteien-vertrag-im-gemueseanbau\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/drei-fragen\\\/markus-bobenhausen-zum-ersten-drei-parteien-vertrag-im-gemueseanbau\\\/&quot;,&quot;element_name&quot;:&quot;Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\\u00fcseanbau&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2021\/12\/markus-bodenhausen.jpg?t=2026071510\"\n                        alt=\"Portr\u00e4t von Markus Bobenhausen\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Markus Bobenhausen \u00a9 REWE Group\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <div><\/div>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">4. Februar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Drei Fragen an<span>Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\u00fcseanbau<\/span><\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47367\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Markus Bobenhausen zum ersten Drei-Parteien-Vertrag im Gem\\u00fcseanbau&quot;,&quot;post_type&quot;:&quot;3questions&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default medium type-post\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/stories\/gruene-woche-2026-starke-signale-fuer-die-landwirtschaft-und-eine-besondere-auszeichnung-fuer-emilie-bourgoin\/\"\n        class=\"post-teaser__inner\"\n                data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/stories\\\/gruene-woche-2026-starke-signale-fuer-die-landwirtschaft-und-eine-besondere-auszeichnung-fuer-emilie-bourgoin\\\/&quot;,&quot;element_name&quot;:&quot;Gr\\u00fcne Woche 2026: Starke Signale f\\u00fcr die Landwirtschaft \\u2013 und eine besondere Auszeichnung f\\u00fcr Emilie Bourgoin\\u00a0\\u00a0&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n                                <div class=\"post-teaser__background-wrapper\">\n                <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/gruene-woche-2026-1.jpg?t=2026071510\"\n                        alt=\"Bild vom REWE Group Messestand auf der Gr\u00fcnen Woche 2026\"\n                        loading=\"lazy\"\n                         data-copyright=\"Bild vom REWE Group Messestand auf der Gr\u00fcnen Woche 2026 \u00a9 REWE Group\" data-copyright-wrapper=\".post-teaser__inner\"                    >\n                <\/div>\n            <\/div>\n                <div class=\"post-teaser__content-wrapper\">\n            <p class=\"post-teaser__type\">Story<\/p>\n                        <div class=\"post-teaser__content\">\n                <p class=\"post-teaser__note\">29. Januar 2026<\/p>\n                <h3 class=\"post-teaser__title\">Gr\u00fcne Woche 2026: Starke Signale f\u00fcr die Landwirtschaft \u2013 und eine besondere Auszeichnung f\u00fcr Emilie Bourgoin\u00a0\u00a0<\/h3>                            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47302\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Gr\\u00fcne Woche 2026: Starke Signale f\\u00fcr die Landwirtschaft \\u2013 und eine besondere Auszeichnung f\\u00fcr Emilie Bourgoin\\u00a0\\u00a0&quot;,&quot;post_type&quot;:&quot;post&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                                    <li class=\"posts-slider__slide medium\">\n                        <div class=\"post-teaser post-teaser_default bg-taupe medium type-3questions\">\n    <a\n        href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/drei-fragen\/bernhard-pointner-zum-drei-parteien-vertrag-beim-zukunftsbauer\/\"\n        class=\"post-teaser__inner text-focus\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_teaser&quot;,&quot;link_url&quot;:&quot;https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/drei-fragen\\\/bernhard-pointner-zum-drei-parteien-vertrag-beim-zukunftsbauer\\\/&quot;,&quot;element_name&quot;:&quot;Bernhard Pointner zum Drei-Parteien-Vertrag beim \\u201eZukunftsbauer\\u201c&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;}\"\n    >\n        <div\n            class=\"new-post-teaser__background-wrapper\"\n                    >\n                                            <div class=\"focused-image-container\">\n                    <img decoding=\"async\"\n                        class=\"focused-image\"\n                        data-focus-x=\"0.00\"\n                        data-focus-y=\"0.00\"\n                        src=\"https:\/\/www.rewe-group.com\/content\/uploads\/2026\/01\/Portareat-von-Bernhard-Pointner.jpg?t=2026071510\"\n                        alt=\"Portr\u00e4t von Bernhard Pointner\"\n                        loading=\"lazy\"\n                         data-copyright=\"Portr\u00e4t von Bernhard Pointner \u00a9 Milchwerke Berchtesgadener Land Chiemgau eG\"                    >\n                <\/div>\n            \n                    <\/div>\n\n        <div class=\"new-post-teaser__content-wrapper\">\n            <div class=\"new-post-teaser__content-inner\">\n                                    <div><\/div>\n                                <div class=\"new-post-teaser__content\">\n                    <p class=\"post-teaser__note\">28. Januar 2026<\/p>\n                    <h3 class=\"post-teaser__title\">Drei Fragen an<span>Bernhard Pointner zum Drei-Parteien-Vertrag beim \u201eZukunftsbauer\u201c<\/span><\/h3>                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/a>\n            <button\n        type=\"button\"\n        class=\"btn-icon icon-add add2basket small\"\n        aria-label=\"in die Sammlung hinzuf\u00fcgen\"\n        data-post-id=\"47214\"\n        data-blog-id=\"2\"\n        data-tracking=\"{&quot;event&quot;:&quot;click_add_to_collection&quot;,&quot;modul_name&quot;:&quot;.teaser-editorial&quot;,&quot;post_title&quot;:&quot;Bernhard Pointner zum Drei-Parteien-Vertrag beim \\u201eZukunftsbauer\\u201c&quot;,&quot;post_type&quot;:&quot;3questions&quot;,&quot;post_category&quot;:&quot;Politik&quot;}\"\n    ><\/button>\n<\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-full-single row-full-single my-row-block row-full\"><div class=\"myblock-wrapper block-my-teaser-kl-linkedin\" data-module-name=\"Teaser KL LinkedIn\"><div class=\"myblock-wrapper\">\n    <div class=\"kl-linkedin-teaser\" data-module-name=\".kl-linkedin-teaser\">\n        <div class=\"contents\">\n            <div class=\"contents-inner\">\n                <h2 class=\"typo-xl\">Das Kompetenzzentrum Landwirtschaft auf  <\/h2>\n                <div class=\"entry-content\">\n                    <p>Im Kompetenzzentrum Landwirtschaft arbeiten Expert:innen aus Landwirtschaft, Wissenschaft Erzeugung, Wirtschaft und Handel gemeinsam an wegweisenden Projekten f\u00fcr die heimische Landwirtschaft. Ein zentrales Thema: der Wandel von der Wertsch\u00f6pfungskette zur Wertsch\u00e4tzungskette. Mehr dazu auf dem LinkedIn-Kanal des Kompetenzzentrum Landwirtschaft.<\/p>\n                <\/div>\n                <p class=\"link\">\n                    <a\n                        href=\"https:\/\/www.linkedin.com\/showcase\/kompetenzzentrum-landwirtschaft\/posts\/?feedView=all\"\n                        class=\"arrow-link btn-white\"\n                        target=\"_blank\" rel=\"noopener noreferrer\"                    >\n                        Zum LinkedIn-Kanal                    <\/a>\n                <\/p>\n            <\/div>\n        <\/div>\n\n        <div class=\"post-teaser post-teaser_default kl-linkedin-pattern\">\n            <div class=\"post-teaser__inner has-illustration\">\n                <div class=\"post-teaser__content-wrapper\">\n                    <div class=\"post-teaser__illustration\"><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Erich Stockhausen ist selbstst\u00e4ndiger REWE-Kaufmann sowie Aufsichtsratsvorsitzender der REWE Group \u2013 und seit diesem Jahr auch Schirmherr des neugegr\u00fcndeten Kompetenzzentrums Landwirtschaft. In der aktuellen Stimme des Monats erkl\u00e4rt er, warum die genossenschaftlichen Werte dem Kompetenzzentrum zum Erfolg verhelfen werden.<\/p>\n","protected":false},"featured_media":30101,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","nl_adhoc_sent":1,"footnotes":""},"categories":[6],"tags":[62,59,41],"focus_theme":[139],"class_list":["post-30144","opinion","type-opinion","status-publish","has-post-thumbnail","hentry","category-politik","tag-genossenschaft","tag-landwirtschaft","tag-regionalitaet","focus_theme-undefined"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c - REWE Group<\/title>\n<meta name=\"description\" content=\"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c\" \/>\n<meta property=\"og:description\" content=\"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"REWE Group\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T08:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen-1024x732.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/\",\"name\":\"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c - REWE Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/05\\\/Erich-Stockhausen.jpg?t=2026071510\",\"datePublished\":\"2023-05-17T12:03:54+00:00\",\"dateModified\":\"2025-09-24T08:45:52+00:00\",\"description\":\"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/05\\\/Erich-Stockhausen.jpg?t=2026071510\",\"contentUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/05\\\/Erich-Stockhausen.jpg?t=2026071510\",\"width\":2500,\"height\":1786,\"caption\":\"Erich Stockhausen ist Aufsichtsrat der REWE Zentralfinanz e.G.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/newsroom\\\/meinungen\\\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\",\"name\":\"REWE Group\",\"description\":\"Die Website der REWE Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c - REWE Group","description":"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c","og_description":"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.","og_url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/","og_site_name":"REWE Group","article_modified_time":"2025-09-24T08:45:52+00:00","og_image":[{"width":1024,"height":732,"url":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen-1024x732.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/","url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/","name":"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c - REWE Group","isPartOf":{"@id":"https:\/\/www.rewe-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/#primaryimage"},"image":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen.jpg?t=2026071510","datePublished":"2023-05-17T12:03:54+00:00","dateModified":"2025-09-24T08:45:52+00:00","description":"Aufsichtsratsvorsitzender Erich Stockhausen erkl\u00e4rt, warum unsere genossenschaftlichen Werte dem Kompetenzzentrum Landwirtschaft zum Erfolg verhelfen werden.","breadcrumb":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/#primaryimage","url":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen.jpg?t=2026071510","contentUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/05\/Erich-Stockhausen.jpg?t=2026071510","width":2500,"height":1786,"caption":"Erich Stockhausen ist Aufsichtsrat der REWE Zentralfinanz e.G."},{"@type":"BreadcrumbList","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/newsroom\/meinungen\/wir-muessen-uns-gemeinsam-auf-den-weg-machen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.rewe-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"\u201eWir m\u00fcssen uns gemeinsam auf den Weg machen\u201c"}]},{"@type":"WebSite","@id":"https:\/\/www.rewe-group.com\/de\/#website","url":"https:\/\/www.rewe-group.com\/de\/","name":"REWE Group","description":"Die Website der REWE Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rewe-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/opinion\/30144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/opinion"}],"about":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/types\/opinion"}],"version-history":[{"count":26,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/opinion\/30144\/revisions"}],"predecessor-version":[{"id":45600,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/opinion\/30144\/revisions\/45600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media\/30101"}],"wp:attachment":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media?parent=30144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/categories?post=30144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/tags?post=30144"},{"taxonomy":"focus_theme","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/focus_theme?post=30144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}