{"id":31274,"date":"2023-06-29T13:05:17","date_gmt":"2023-06-29T11:05:17","guid":{"rendered":"https:\/\/www.rewe-group.com\/de\/?post_type=company_report&#038;p=31274"},"modified":"2025-07-04T09:45:18","modified_gmt":"2025-07-04T07:45:18","slug":"nachhaltigkeitsbericht-2022","status":"publish","type":"company_report","link":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/","title":{"rendered":"Nachhaltigkeitsbericht 2022"},"content":{"rendered":"\n<div class=\"wp-block-myblocks-template-root template-root\">\n<div class=\"wp-block-myblocks-section block-section section-bg-white section-padding-top section-padding-bottom\">\n<div class=\"wp-block-myblocks-row-margin-aside row-margin-aside my-row-block row-margin\">\n<div class=\"wp-block-myblocks-row-margin-aside-cell-aside row-cell row-margin-aside-cell-aside my-cell-block\"><\/div>\n\n\n\n<div class=\"wp-block-myblocks-row-margin-aside-cell-main row-cell row-margin-aside-cell-main my-cell-block\"><div class=\"myblock-wrapper block-my-text-block block-ingrid\" data-module-name=\"Headline Copy Link\">    <div class=\"textblock margin-row-inner\">\n        <div class=\"entry-content\">\n            \n            <p>Die REWE Group handelt umwelt- und klimabewusst, f\u00f6rdert nachhaltigere Sortimente, achtet auf einen fairen Umgang mit Partnern und Lieferanten, \u00fcbernimmt Verantwortung f\u00fcr ihre Mitarbeitenden und setzt sich f\u00fcr eine zukunftsf\u00e4hige Gesellschaft ein. Dieser Bericht zeigt, wie das Unternehmen 2022 seine Nachhaltigkeitsstrategie umgesetzt hat \u2013 und zuk\u00fcnftigen Herausforderungen begegnen will.<\/p>\n        <\/div>\n\n                    <div class=\"textblock__links\">\n                <a\n                    href=\"https:\/\/www.rewe-group.com\/content\/uploads\/2025\/07\/REWE_Group-Nachhaltigkeitsbericht_2022.pdf?t=2025070407\"\n                    target=\"_blank\" rel=\"noopener noreferrer\"                    class=\"arrow-link\"\n                >\n                    Zum Nachhaltigkeitsbericht                <\/a>\n            <\/div>\n            <\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":31281,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","nl_adhoc_sent":1,"footnotes":""},"categories":[5],"tags":[33],"sales_line":[19],"focus_theme":[139],"class_list":["post-31274","company_report","type-company_report","status-publish","has-post-thumbnail","hentry","category-nachhaltigkeit","tag-nachhaltigkeitsziele","sales_line-rewe-group","focus_theme-undefined"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nachhaltigkeitsbericht 2022 - REWE Group<\/title>\n<meta name=\"description\" content=\"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltigkeitsbericht 2022\" \/>\n<meta property=\"og:description\" content=\"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"REWE Group\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T07:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/06\/nachhaltigkeitsbericht-2022-1024x575.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/\",\"name\":\"Nachhaltigkeitsbericht 2022 - REWE Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/06\\\/nachhaltigkeitsbericht-2022.jpg?t=2026071501\",\"datePublished\":\"2023-06-29T11:05:17+00:00\",\"dateModified\":\"2025-07-04T07:45:18+00:00\",\"description\":\"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/06\\\/nachhaltigkeitsbericht-2022.jpg?t=2026071501\",\"contentUrl\":\"https:\\\/\\\/www.rewe-group.com\\\/content\\\/uploads\\\/2023\\\/06\\\/nachhaltigkeitsbericht-2022.jpg?t=2026071501\",\"width\":2560,\"height\":1438,\"caption\":\"Die REWE Group handelt umwelt- und klimabewusst, f\u00f6rdert nachhaltigere Sortimente, achtet auf einen fairen Umgang mit Partnern und Lieferanten, \u00fcbernimmt Verantwortung f\u00fcr ihre Mitarbeitenden und setzt sich f\u00fcr eine zukunftsf\u00e4hige Gesellschaft ein. Dieser Bericht zeigt, wie das Unternehmen 2022 seine Nachhaltigkeitsstrategie umgesetzt hat \u2013 und zuk\u00fcnftigen Herausforderungen begegnen will.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/presse-und-medien\\\/publikationen\\\/unternehmensreporte\\\/nachhaltigkeitsbericht-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltigkeitsbericht 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/\",\"name\":\"REWE Group\",\"description\":\"Die Website der REWE Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rewe-group.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nachhaltigkeitsbericht 2022 - REWE Group","description":"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/","og_locale":"de_DE","og_type":"article","og_title":"Nachhaltigkeitsbericht 2022","og_description":"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.","og_url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/","og_site_name":"REWE Group","article_modified_time":"2025-07-04T07:45:18+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/06\/nachhaltigkeitsbericht-2022-1024x575.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/","url":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/","name":"Nachhaltigkeitsbericht 2022 - REWE Group","isPartOf":{"@id":"https:\/\/www.rewe-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/06\/nachhaltigkeitsbericht-2022.jpg?t=2026071501","datePublished":"2023-06-29T11:05:17+00:00","dateModified":"2025-07-04T07:45:18+00:00","description":"REWE Group: Unser Nachhaltigkeitsbericht beschreibt die Aktivit\u00e4ten des letzten Gesch\u00e4ftsjahres und blickt auf zuk\u00fcnftige Herausforderungen.","breadcrumb":{"@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/#primaryimage","url":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/06\/nachhaltigkeitsbericht-2022.jpg?t=2026071501","contentUrl":"https:\/\/www.rewe-group.com\/content\/uploads\/2023\/06\/nachhaltigkeitsbericht-2022.jpg?t=2026071501","width":2560,"height":1438,"caption":"Die REWE Group handelt umwelt- und klimabewusst, f\u00f6rdert nachhaltigere Sortimente, achtet auf einen fairen Umgang mit Partnern und Lieferanten, \u00fcbernimmt Verantwortung f\u00fcr ihre Mitarbeitenden und setzt sich f\u00fcr eine zukunftsf\u00e4hige Gesellschaft ein. Dieser Bericht zeigt, wie das Unternehmen 2022 seine Nachhaltigkeitsstrategie umgesetzt hat \u2013 und zuk\u00fcnftigen Herausforderungen begegnen will."},{"@type":"BreadcrumbList","@id":"https:\/\/www.rewe-group.com\/de\/presse-und-medien\/publikationen\/unternehmensreporte\/nachhaltigkeitsbericht-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.rewe-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nachhaltigkeitsbericht 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.rewe-group.com\/de\/#website","url":"https:\/\/www.rewe-group.com\/de\/","name":"REWE Group","description":"Die Website der REWE Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rewe-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/company_report\/31274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/company_report"}],"about":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/types\/company_report"}],"version-history":[{"count":9,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/company_report\/31274\/revisions"}],"predecessor-version":[{"id":44713,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/company_report\/31274\/revisions\/44713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media\/31281"}],"wp:attachment":[{"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/media?parent=31274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/categories?post=31274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/tags?post=31274"},{"taxonomy":"sales_line","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/sales_line?post=31274"},{"taxonomy":"focus_theme","embeddable":true,"href":"https:\/\/www.rewe-group.com\/de\/wp-json\/wp\/v2\/focus_theme?post=31274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}